{"id":10339,"date":"2022-04-26T17:26:42","date_gmt":"2022-04-26T15:26:42","guid":{"rendered":"https:\/\/www.it-rack.it\/?p=10339"},"modified":"2022-04-26T17:29:13","modified_gmt":"2022-04-26T15:29:13","slug":"itrack-entra-nella-vendor-list-della-nato","status":"publish","type":"post","link":"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/","title":{"rendered":"ITRack enters the NATO Vendor List"},"content":{"rendered":"<div class=\"container page-styling row-wrap-container row-wrap-nottl\"><div class=\"vc_row wpb_row vc_row-fluid row-container\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>With the aim of distinguishing itself in the market and facilitating the proposition of ITRack branded products to all our Partners also in the NATO and Defense field, we are proud to announce that we have recently obtained the NCAGE CODE (NATO Commercial And Government Entity Code) issued by the Ministry of the Defense through the Central Coding Organization (OCC), a code that allows to identify, within the NATO coding system, the companies that can entertain commercial relations with the Defense Administrations.<\/p>\n<p>&nbsp;<\/p>\n<p>With the attribution of the Commercial and Government Entity (CAGE) Code, ITRack products are recognized as compliant with certain quality standards, thus allowing ITRack to be positioned among a small number of suppliers of the Armed Forces and of NATO bases, both on Italian territory, and on all the territories and nations that adhere to NATO.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"With the aim of distinguishing itself in the market and facilitating the proposition of ITRack branded products to all our Partners","protected":false},"author":2,"featured_media":10341,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[45],"tags":[759,770],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IT-RACK ITRack entra nella Vendor List della NATO News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IT-RACK ITRack entra nella Vendor List della NATO News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/\" \/>\n<meta property=\"og:site_name\" content=\"IT-RACK\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T15:26:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-26T15:29:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.it-rack.it\/wp-content\/uploads\/2022\/04\/Nato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"luca.brunco@it-rack.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"luca.brunco@it-rack.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/\"},\"author\":{\"name\":\"luca.brunco@it-rack.it\",\"@id\":\"https:\/\/www.it-rack.it\/en\/#\/schema\/person\/ec2bf1bd04654e39644b4794fc934211\"},\"headline\":\"ITRack entra nella Vendor List della NATO\",\"datePublished\":\"2022-04-26T15:26:42+00:00\",\"dateModified\":\"2022-04-26T15:29:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/\"},\"wordCount\":155,\"publisher\":{\"@id\":\"https:\/\/www.it-rack.it\/en\/#organization\"},\"keywords\":[\"Armadi rack 19\\\"\",\"Partnership\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/\",\"url\":\"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/\",\"name\":\"IT-RACK ITRack entra nella Vendor List della NATO News\",\"isPartOf\":{\"@id\":\"https:\/\/www.it-rack.it\/en\/#website\"},\"datePublished\":\"2022-04-26T15:26:42+00:00\",\"dateModified\":\"2022-04-26T15:29:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.it-rack.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITRack entra nella Vendor List della NATO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.it-rack.it\/en\/#website\",\"url\":\"https:\/\/www.it-rack.it\/en\/\",\"name\":\"IT-RACK\",\"description\":\"Armadi Rack ad alto contenuto tecnologico\",\"publisher\":{\"@id\":\"https:\/\/www.it-rack.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.it-rack.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.it-rack.it\/en\/#organization\",\"name\":\"IT-Rack\",\"url\":\"https:\/\/www.it-rack.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.it-rack.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.it-rack.it\/wp-content\/uploads\/2020\/10\/ITRack.jpg\",\"contentUrl\":\"https:\/\/www.it-rack.it\/wp-content\/uploads\/2020\/10\/ITRack.jpg\",\"width\":2000,\"height\":484,\"caption\":\"IT-Rack\"},\"image\":{\"@id\":\"https:\/\/www.it-rack.it\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.it-rack.it\/en\/#\/schema\/person\/ec2bf1bd04654e39644b4794fc934211\",\"name\":\"luca.brunco@it-rack.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.it-rack.it\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d29f8237a878c3fd1d358abb14168d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d29f8237a878c3fd1d358abb14168d9?s=96&d=mm&r=g\",\"caption\":\"luca.brunco@it-rack.it\"},\"url\":\"https:\/\/www.it-rack.it\/en\/author\/luca-bruncoit-rack-it\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IT-RACK ITRack entra nella Vendor List della NATO News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/","og_locale":"en_GB","og_type":"article","og_title":"IT-RACK ITRack entra nella Vendor List della NATO News","og_url":"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/","og_site_name":"IT-RACK","article_published_time":"2022-04-26T15:26:42+00:00","article_modified_time":"2022-04-26T15:29:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.it-rack.it\/wp-content\/uploads\/2022\/04\/Nato.jpg","type":"image\/jpeg"}],"author":"luca.brunco@it-rack.it","twitter_card":"summary_large_image","twitter_misc":{"Written by":"luca.brunco@it-rack.it","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/#article","isPartOf":{"@id":"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/"},"author":{"name":"luca.brunco@it-rack.it","@id":"https:\/\/www.it-rack.it\/en\/#\/schema\/person\/ec2bf1bd04654e39644b4794fc934211"},"headline":"ITRack entra nella Vendor List della NATO","datePublished":"2022-04-26T15:26:42+00:00","dateModified":"2022-04-26T15:29:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/"},"wordCount":155,"publisher":{"@id":"https:\/\/www.it-rack.it\/en\/#organization"},"keywords":["Armadi rack 19\"","Partnership"],"articleSection":["News"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/","url":"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/","name":"IT-RACK ITRack entra nella Vendor List della NATO News","isPartOf":{"@id":"https:\/\/www.it-rack.it\/en\/#website"},"datePublished":"2022-04-26T15:26:42+00:00","dateModified":"2022-04-26T15:29:13+00:00","breadcrumb":{"@id":"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.it-rack.it\/en\/itrack-entra-nella-vendor-list-della-nato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.it-rack.it\/"},{"@type":"ListItem","position":2,"name":"ITRack entra nella Vendor List della NATO"}]},{"@type":"WebSite","@id":"https:\/\/www.it-rack.it\/en\/#website","url":"https:\/\/www.it-rack.it\/en\/","name":"IT-RACK","description":"Armadi Rack ad alto contenuto tecnologico","publisher":{"@id":"https:\/\/www.it-rack.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.it-rack.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.it-rack.it\/en\/#organization","name":"IT-Rack","url":"https:\/\/www.it-rack.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.it-rack.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.it-rack.it\/wp-content\/uploads\/2020\/10\/ITRack.jpg","contentUrl":"https:\/\/www.it-rack.it\/wp-content\/uploads\/2020\/10\/ITRack.jpg","width":2000,"height":484,"caption":"IT-Rack"},"image":{"@id":"https:\/\/www.it-rack.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.it-rack.it\/en\/#\/schema\/person\/ec2bf1bd04654e39644b4794fc934211","name":"luca.brunco@it-rack.it","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.it-rack.it\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d29f8237a878c3fd1d358abb14168d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d29f8237a878c3fd1d358abb14168d9?s=96&d=mm&r=g","caption":"luca.brunco@it-rack.it"},"url":"https:\/\/www.it-rack.it\/en\/author\/luca-bruncoit-rack-it\/"}]}},"_links":{"self":[{"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/posts\/10339"}],"collection":[{"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/comments?post=10339"}],"version-history":[{"count":4,"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/posts\/10339\/revisions"}],"predecessor-version":[{"id":10344,"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/posts\/10339\/revisions\/10344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/media\/10341"}],"wp:attachment":[{"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/media?parent=10339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/categories?post=10339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.it-rack.it\/en\/wp-json\/wp\/v2\/tags?post=10339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}